{"id":80774,"date":"2025-05-19T13:24:42","date_gmt":"2025-05-19T11:24:42","guid":{"rendered":"https:\/\/www.isquad.info\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/"},"modified":"2025-05-19T13:24:42","modified_gmt":"2025-05-19T11:24:42","slug":"sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera","status":"publish","type":"post","link":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/","title":{"rendered":"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera"},"content":{"rendered":"<p>Coordinare gli elenchi delle delegazioni nazionali, la gestione del registro e la pianificazione degli eventi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coordinare gli elenchi delle delegazioni nazionali, la gestione del registro e la pianificazione degli eventi.<\/p>\n","protected":false},"author":2,"featured_media":28851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"two_page_speed":[],"footnotes":""},"categories":[860],"tags":[1916,865,867,1915,868],"class_list":["post-80774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletica","tag-erp-di-atletica","tag-piattaforma-di-atletica","tag-sistema-di-atletica","tag-software-di-atletica","tag-suite-di-atletica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera\" \/>\n<meta property=\"og:description\" content=\"Coordinare gli elenchi delle delegazioni nazionali, la gestione del registro e la pianificazione degli eventi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/\" \/>\n<meta property=\"og:site_name\" content=\"iSquad\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T11:24:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"520\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mute\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@toools_es\" \/>\n<meta name=\"twitter:site\" content=\"@toools_es\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/","og_locale":"it_IT","og_type":"article","og_title":"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera","og_description":"Coordinare gli elenchi delle delegazioni nazionali, la gestione del registro e la pianificazione degli eventi.","og_url":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/","og_site_name":"iSquad","article_published_time":"2025-05-19T11:24:42+00:00","og_image":[{"width":520,"height":520,"url":"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png","type":"image\/png"}],"author":"Mute","twitter_card":"summary_large_image","twitter_creator":"@toools_es","twitter_site":"@toools_es","twitter_misc":{"Scritto da":"Mute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#article","isPartOf":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/"},"author":{"name":"Mute","@id":"https:\/\/www.isquad.info\/it\/#\/schema\/person\/e687f0a57ada70b7ae84d1e62ee5f58e"},"headline":"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera","datePublished":"2025-05-19T11:24:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/"},"wordCount":26,"publisher":{"@id":"https:\/\/www.isquad.info\/it\/#organization"},"image":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/athletics-1.png","keywords":["ERP di atletica","piattaforma di atletica","sistema di atletica","software di atletica","suite di atletica"],"articleSection":["Atletica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/","url":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/","name":"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera","isPartOf":{"@id":"https:\/\/www.isquad.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#primaryimage"},"image":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/athletics-1.png","datePublished":"2025-05-19T11:24:42+00:00","breadcrumb":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#primaryimage","url":"https:\/\/www.isquad.info\/wp-content\/uploads\/athletics-1.png","contentUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/athletics-1.png","width":1904,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.isquad.info\/it\/sistema-di-supervisione-e-rappresentanza-delle-delegazioni-nazionali-di-atletica-leggera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.isquad.info\/it\/"},{"@type":"ListItem","position":2,"name":"Sistema di supervisione e rappresentanza delle delegazioni nazionali di atletica leggera"}]},{"@type":"WebSite","@id":"https:\/\/www.isquad.info\/it\/#website","url":"https:\/\/www.isquad.info\/it\/","name":"iSquad","description":"Multiplatform Sports Management and Analysis","publisher":{"@id":"https:\/\/www.isquad.info\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.isquad.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.isquad.info\/it\/#organization","name":"iSquad","url":"https:\/\/www.isquad.info\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.isquad.info\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png","contentUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png","width":520,"height":520,"caption":"iSquad"},"image":{"@id":"https:\/\/www.isquad.info\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/toools_es","https:\/\/www.linkedin.com\/company\/toools\/","https:\/\/www.instagram.com\/toools_es\/","https:\/\/www.youtube.com\/user\/Tooolssl"]},{"@type":"Person","@id":"https:\/\/www.isquad.info\/it\/#\/schema\/person\/e687f0a57ada70b7ae84d1e62ee5f58e","name":"Mute","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad32aea83c66eb8da5020525587042ee8566e6ca155655f7a055c49a241342e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad32aea83c66eb8da5020525587042ee8566e6ca155655f7a055c49a241342e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad32aea83c66eb8da5020525587042ee8566e6ca155655f7a055c49a241342e7?s=96&d=mm&r=g","caption":"Mute"},"url":"https:\/\/www.isquad.info\/it\/author\/mute\/"}]}},"_links":{"self":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/posts\/80774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/comments?post=80774"}],"version-history":[{"count":0,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/posts\/80774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/media\/28851"}],"wp:attachment":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/media?parent=80774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/categories?post=80774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/tags?post=80774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}