{"id":80049,"date":"2025-05-19T13:21:54","date_gmt":"2025-05-19T11:21:54","guid":{"rendered":"https:\/\/www.isquad.info\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/"},"modified":"2025-05-19T13:21:54","modified_gmt":"2025-05-19T11:21:54","slug":"sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative","status":"publish","type":"post","link":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/","title":{"rendered":"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative"},"content":{"rendered":"<p>Gestire le convocazioni e i dati delle selezioni con un quadro unificato per le selezioni di pallavolo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestire le convocazioni e i dati delle selezioni con un quadro unificato per le selezioni di pallavolo.<\/p>\n","protected":false},"author":2,"featured_media":28853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"two_page_speed":[],"footnotes":""},"categories":[1385],"tags":[1902,1903,1901,1900,1904],"class_list":["post-80049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pallavolo","tag-erp-per-pallavolo","tag-piattaforma-per-pallavolo","tag-sistema-per-pallavolo","tag-software-per-pallavolo","tag-suite-per-pallavolo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative\" \/>\n<meta property=\"og:description\" content=\"Gestire le convocazioni e i dati delle selezioni con un quadro unificato per le selezioni di pallavolo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/\" \/>\n<meta property=\"og:site_name\" content=\"iSquad\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T11:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"520\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mute\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@toools_es\" \/>\n<meta name=\"twitter:site\" content=\"@toools_es\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/","og_locale":"it_IT","og_type":"article","og_title":"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative","og_description":"Gestire le convocazioni e i dati delle selezioni con un quadro unificato per le selezioni di pallavolo.","og_url":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/","og_site_name":"iSquad","article_published_time":"2025-05-19T11:21:54+00:00","og_image":[{"width":520,"height":520,"url":"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png","type":"image\/png"}],"author":"Mute","twitter_card":"summary_large_image","twitter_creator":"@toools_es","twitter_site":"@toools_es","twitter_misc":{"Scritto da":"Mute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#article","isPartOf":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/"},"author":{"name":"Mute","@id":"https:\/\/www.isquad.info\/it\/#\/schema\/person\/e687f0a57ada70b7ae84d1e62ee5f58e"},"headline":"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative","datePublished":"2025-05-19T11:21:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/"},"wordCount":30,"publisher":{"@id":"https:\/\/www.isquad.info\/it\/#organization"},"image":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/Volleyball-management-software-for-federations-leagues-and-clubs.png","keywords":["erp per pallavolo","piattaforma per pallavolo","sistema per pallavolo","software per pallavolo","suite per pallavolo"],"articleSection":["Pallavolo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/","url":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/","name":"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative","isPartOf":{"@id":"https:\/\/www.isquad.info\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#primaryimage"},"image":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/Volleyball-management-software-for-federations-leagues-and-clubs.png","datePublished":"2025-05-19T11:21:54+00:00","breadcrumb":{"@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#primaryimage","url":"https:\/\/www.isquad.info\/wp-content\/uploads\/Volleyball-management-software-for-federations-leagues-and-clubs.png","contentUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/Volleyball-management-software-for-federations-leagues-and-clubs.png","width":1904,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.isquad.info\/it\/sistema-di-selezione-della-pallavolo-per-la-gestione-delle-formazioni-nazionali-e-rappresentative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.isquad.info\/it\/"},{"@type":"ListItem","position":2,"name":"Sistema di selezione della pallavolo per la gestione delle formazioni nazionali e rappresentative"}]},{"@type":"WebSite","@id":"https:\/\/www.isquad.info\/it\/#website","url":"https:\/\/www.isquad.info\/it\/","name":"iSquad","description":"Multiplatform Sports Management and Analysis","publisher":{"@id":"https:\/\/www.isquad.info\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.isquad.info\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.isquad.info\/it\/#organization","name":"iSquad","url":"https:\/\/www.isquad.info\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.isquad.info\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png","contentUrl":"https:\/\/www.isquad.info\/wp-content\/uploads\/2025\/04\/favicon.png","width":520,"height":520,"caption":"iSquad"},"image":{"@id":"https:\/\/www.isquad.info\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/toools_es","https:\/\/www.linkedin.com\/company\/toools\/","https:\/\/www.instagram.com\/toools_es\/","https:\/\/www.youtube.com\/user\/Tooolssl"]},{"@type":"Person","@id":"https:\/\/www.isquad.info\/it\/#\/schema\/person\/e687f0a57ada70b7ae84d1e62ee5f58e","name":"Mute","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ad32aea83c66eb8da5020525587042ee8566e6ca155655f7a055c49a241342e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad32aea83c66eb8da5020525587042ee8566e6ca155655f7a055c49a241342e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad32aea83c66eb8da5020525587042ee8566e6ca155655f7a055c49a241342e7?s=96&d=mm&r=g","caption":"Mute"},"url":"https:\/\/www.isquad.info\/it\/author\/mute\/"}]}},"_links":{"self":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/posts\/80049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/comments?post=80049"}],"version-history":[{"count":0,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/posts\/80049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/media\/28853"}],"wp:attachment":[{"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/media?parent=80049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/categories?post=80049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isquad.info\/it\/wp-json\/wp\/v2\/tags?post=80049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}